{"id":5234,"date":"2015-03-20T02:19:21","date_gmt":"2015-03-19T17:19:21","guid":{"rendered":"http:\/\/canopusdrums.com\/jp\/wp2023\/?post_type=endorser-j&#038;p=5234"},"modified":"2016-03-24T14:02:21","modified_gmt":"2016-03-24T05:02:21","slug":"kuhara_kazuyuki","status":"publish","type":"endorser-j","link":"https:\/\/canopusdrums.com\/jp\/endorser-j\/kuhara_kazuyuki\/","title":{"rendered":"\u30af\u30cf\u30e9\u30ab\u30ba\u30e6\u30ad"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4957,"parent":0,"menu_order":127,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-5234","endorser-j","type-endorser-j","status-publish","format-standard","has-post-thumbnail","hentry","endorser-name-tag-167","endorser-j-cat-jk"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/endorser-j\/5234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/endorser-j"}],"about":[{"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/types\/endorser-j"}],"author":[{"embeddable":true,"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/comments?post=5234"}],"version-history":[{"count":0,"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/endorser-j\/5234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/media\/4957"}],"wp:attachment":[{"href":"https:\/\/canopusdrums.com\/jp\/wp-json\/wp\/v2\/media?parent=5234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}